{"id":9242,"date":"2026-05-12T10:54:05","date_gmt":"2026-05-12T13:54:05","guid":{"rendered":"https:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/?p=9242"},"modified":"2026-05-12T11:04:01","modified_gmt":"2026-05-12T14:04:01","slug":"programa-trainee-kerry-2026","status":"publish","type":"post","link":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/programa-trainee-kerry-2026\/","title":{"rendered":"\u25ba Programa Trainee Kerry 2026 para rec\u00e9m-formados"},"content":{"rendered":"<p>Segue abaixo informa\u00e7\u00f5es que recebemos da Cia de Talentos para divulga\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p class=\"x_MsoNormal\"><b data-olk-copy-source=\"MessageBody\">Programa de Trainee Kerry 2026<\/b>\u00a0junto aos <strong>rec\u00e9m-formados<\/strong> da institui\u00e7\u00e3o.<\/p>\n<p class=\"x_MsoNormal\"><b>Programa de Trainee Kerry 2026<\/b><\/p>\n<p class=\"x_MsoNormal\">A Kerry \u00e9 uma l\u00edder global em nutri\u00e7\u00e3o sustent\u00e1vel para as ind\u00fastrias de alimentos, bebidas e farmac\u00eautica. Presente em mais de 50 pa\u00edses e com mais de 19 mil colaboradores ao redor do mundo, desenvolve solu\u00e7\u00f5es inovadoras que unem ci\u00eancia, sabor, nutri\u00e7\u00e3o e sustentabilidade para impactar positivamente bilh\u00f5es de pessoas.<\/p>\n<p class=\"x_MsoNormal\">Guiada pelo prop\u00f3sito\u00a0<i>Inspiring Food, Nourishing Life<\/i>, a Kerry acredita no potencial de novos talentos para construir o futuro da nutri\u00e7\u00e3o sustent\u00e1vel.<\/p>\n<p class=\"x_MsoNormal\"><b>Sobre o Programa<\/b><\/p>\n<p class=\"x_MsoNormal\">O Programa de Trainee Kerry 2026 foi desenvolvido para acelerar a carreira de talentos com perfil anal\u00edtico, colaborativo e vis\u00e3o de neg\u00f3cio, oferecendo uma jornada estruturada de desenvolvimento ao longo de 2 anos.<\/p>\n<p class=\"x_MsoNormal\">Durante o programa, as pessoas trainees ter\u00e3o contato com projetos estrat\u00e9gicos, exposi\u00e7\u00e3o \u00e0 lideran\u00e7a, experi\u00eancias em diferentes \u00e1reas do neg\u00f3cio e desenvolvimento baseado no modelo 70:20:10.<\/p>\n<p class=\"x_MsoNormal\"><b>Trilhas do programa<\/b><\/p>\n<p class=\"x_MsoNormal\">\u2022\u00a0Trainee Qualidade \u2013 Tr\u00eas Cora\u00e7\u00f5es\/MG<br \/>\n\u2022\u00a0Trainee Vendas \u2013 Campinas\/SP<\/p>\n<p class=\"x_MsoNormal\"><b>Pr\u00e9-requisitos<\/b><\/p>\n<p class=\"x_MsoNormal\">\u2022 Forma\u00e7\u00e3o superior (bacharelado ou licenciatura) conclu\u00edda entre dez\/2022 e jun\/2025 nos cursos de:<\/p>\n<p class=\"x_MsoNormal\">\u2192 Engenharias: Mec\u00e2nica, Alimentos, Produ\u00e7\u00e3o, Processos, Qu\u00edmica, Biotecnologia e Bioqu\u00edmica;<\/p>\n<p class=\"x_MsoNormal\">\u2192 Qu\u00edmica, Biologia, Farm\u00e1cia, Nutri\u00e7\u00e3o e Ci\u00eancia dos Alimentos;<\/p>\n<p class=\"x_MsoNormal\">\u2022 Ingl\u00eas avan\u00e7ado;<\/p>\n<p class=\"x_MsoNormal\">\u2022 Disponibilidade para mudan\u00e7a de cidade\/estado a partir de junho de 2026 e ao longo do programa.<\/p>\n<p class=\"x_MsoNormal\"><b>Os candidatos podem acessar mais informa\u00e7\u00f5es e realizar a inscri\u00e7\u00e3o pelo link<\/b>:\u00a0<u><a id=\"anchor-d24c3308-ce18-3682-ef5b-73e81c2aecca\" title=\"https:\/\/bit.ly\/41RcGyD\" href=\"https:\/\/bit.ly\/41RcGyD\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">https:\/\/bit.ly\/41RcGyD<\/a><\/u><\/p>\n<p class=\"x_MsoNormal\">Contamos com o apoio de voc\u00eas para compartilhar essa oportunidade com seus alunos e alunas.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>Publicado em 12\/05\/2026<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segue abaixo informa\u00e7\u00f5es que recebemos da Cia de Talentos para divulga\u00e7\u00e3o. &nbsp; &nbsp; Programa de Trainee Kerry 2026\u00a0junto aos rec\u00e9m-formados da institui\u00e7\u00e3o. Programa de Trainee Kerry 2026 A Kerry \u00e9 uma l\u00edder global em nutri\u00e7\u00e3o sustent\u00e1vel para as ind\u00fastrias de alimentos, bebidas e farmac\u00eautica. Presente em mais de 50 pa\u00edses e com mais de 19 [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-9242","post","type-post","status-publish","format-standard","hentry","category-estagio"],"_links":{"self":[{"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/posts\/9242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/comments?post=9242"}],"version-history":[{"count":3,"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/posts\/9242\/revisions"}],"predecessor-version":[{"id":9244,"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/posts\/9242\/revisions\/9244"}],"wp:attachment":[{"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/media?parent=9242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/categories?post=9242"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.quimica.ufpr.br\/paginas\/graduacao\/wp-json\/wp\/v2\/tags?post=9242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}